{"id":2307,"date":"2021-11-25T15:27:20","date_gmt":"2021-11-25T18:27:20","guid":{"rendered":"https:\/\/comsefaz.org.br\/?p=2307"},"modified":"2021-11-25T15:27:20","modified_gmt":"2021-11-25T18:27:20","slug":"comsefaz-pede-ao-stf-modulacao-da-decisao-que-reduz-icms-sobre-energia-e-telecomunicacoes","status":"publish","type":"post","link":"https:\/\/comsefaz.org.br\/novo\/comsefaz-pede-ao-stf-modulacao-da-decisao-que-reduz-icms-sobre-energia-e-telecomunicacoes\/","title":{"rendered":"Comsefaz pede ao STF modula\u00e7\u00e3o da decis\u00e3o que reduz ICMS sobre energia e telecomunica\u00e7\u00f5es"},"content":{"rendered":"\n<p>O Comsefaz (Comit\u00ea Nacional dos Secret\u00e1rios de Fazenda dos Estados e do Distrito Federal) divulgou nesta quarta-feira (24) <a href=\"https:\/\/comsefaz.org.br\/wp-content\/uploads\/2021\/11\/Carta-Secretarios-RE-714.139-SC-v3.pdf\">carta em que pede a modula\u00e7\u00e3o da decis\u00e3o do Supremo Tribunal Federal (STF)<\/a> que reconheceu a inconstitucionalidade da institui\u00e7\u00e3o de uma al\u00edquota de ICMS (Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os) majorada para energia el\u00e9trica e telecomunica\u00e7\u00f5es.\u00a0<\/p>\n\n\n\n<p>A decis\u00e3o saiu nos autos do Recurso Extraordin\u00e1rio (RE) 714.139\/SC, cujo julgamento virtual foi finalizado na \u00faltima segunda-feira (22). O Comsefaz defende que a modula\u00e7\u00e3o dos efeitos da decis\u00e3o alinhe-se ao prazo de vig\u00eancia dos Planos Plurianuais (PPAs) de todos os Estados. \u201cO PPA \u00e9 o instrumento fundamental de planejamento de m\u00e9dio prazo, pensado para um per\u00edodo de quatro anos, onde s\u00e3o estimadas as metas e programas a serem cumpridos neste per\u00edodo\u201d, explica.<\/p>\n\n\n\n<p>\u201cDessa forma, caso n\u00e3o seja poss\u00edvel a modula\u00e7\u00e3o, todos os PPAs aprovados em 2020, com vig\u00eancia a partir deste ano, e v\u00e1lidos at\u00e9 2023, restar\u00e3o inviabilizados em suas diretrizes, objetivos e metas\u201d, diz o documento. A carta \u00e9 assinada pelos secret\u00e1rios de Fazenda dos 26 Estados e do Distrito Federal.<\/p>\n\n\n\n<p>Eles alertam que a decis\u00e3o implica \u201cem graves e iminentes consequ\u00eancias para a higidez or\u00e7ament\u00e1ria e financeira dos entes subnacionais, notadamente em face da fixa\u00e7\u00e3o de tese de repercuss\u00e3o geral (Tema 745)\u201d, que determina que o julgado deve ser seguido pelos tribunais de todo o pa\u00eds em casos semelhantes. Ainda durante o julgamento da mat\u00e9ria, <a href=\"https:\/\/comsefaz.org.br\/?p=1703\">os Estados alertaram para as perdas de receitas<\/a> e <a href=\"https:\/\/comsefaz.org.br\/?p=1694\">pediram ao STF a rejei\u00e7\u00e3o do recurso extraordin\u00e1rio<\/a>. <\/p>\n\n\n\n<p>De acordo com o Comsefaz, a decis\u00e3o do STF ter\u00e1 impacto grav\u00edssimo nas finan\u00e7as p\u00fablicas, com repercuss\u00e3o direta na qualidade dos servi\u00e7os p\u00fablicos oferecidos \u00e0 popula\u00e7\u00e3o, pois reduzir\u00e1 a possibilidade de tributa\u00e7\u00e3o na energia el\u00e9trica e nas comunica\u00e7\u00f5es que representam os setores que mais trazem arrecada\u00e7\u00e3o aos entes, juntamente com os combust\u00edveis. \u201cS\u00f3 para ter uma dimens\u00e3o do impacto financeiro, a redu\u00e7\u00e3o das al\u00edquotas em decorr\u00eancia da decis\u00e3o significar\u00e1 uma perda de R$ 27 bilh\u00f5es por ano para os entes\u201d, diz o documento. <\/p>\n\n\n\n<p>A carta alerta ainda que as perdas afetar\u00e3o n\u00e3o s\u00f3 os Estados e o Distrito Federal, mas tamb\u00e9m os Munic\u00edpios, que recebem sua quota-parte do ICMS arrecadado, \u201cressaltando-se que, para alguns deles, a receita da\u00ed decorrente \u00e9, sen\u00e3o a \u00fanica, a mais representativa fonte de financiamento das pol\u00edticas p\u00fablicas.<\/p>\n\n\n\n<p>Veja <a href=\"https:\/\/comsefaz.org.br\/wp-content\/uploads\/2021\/11\/Carta-Secretarios-RE-714.139-SC-v3.pdf\">aqui a Carta do Comsefaz<\/a> na \u00edntegra.<\/p>\n\n\n\n<p><em>(Foto: Nelson J\u00fanior\/SCO\/STF)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Comsefaz (Comit\u00ea Nacional dos Secret\u00e1rios de Fazenda dos Estados e do Distrito Federal) divulgou nesta quarta-feira (24) carta em que pede a modula\u00e7\u00e3o da decis\u00e3o do Supremo Tribunal Federal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2308,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[110],"class_list":["post-2307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-receitas-tributarias"],"acf":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/comsefaz.org.br\/novo\/wp-content\/uploads\/2021\/11\/Luiz-Fux-scaled-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/posts\/2307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/comments?post=2307"}],"version-history":[{"count":0,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/posts\/2307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/media\/2308"}],"wp:attachment":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/media?parent=2307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/categories?post=2307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/tags?post=2307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}