{"id":2317,"date":"2021-11-29T13:25:10","date_gmt":"2021-11-29T16:25:10","guid":{"rendered":"https:\/\/comsefaz.org.br\/?p=2317"},"modified":"2021-11-29T13:25:10","modified_gmt":"2021-11-29T16:25:10","slug":"estados-defendem-flexibilizacao-de-regras-do-teto-de-gastos-em-audiencia-publica-no-senado","status":"publish","type":"post","link":"https:\/\/comsefaz.org.br\/novo\/estados-defendem-flexibilizacao-de-regras-do-teto-de-gastos-em-audiencia-publica-no-senado\/","title":{"rendered":"Estados defendem flexibiliza\u00e7\u00e3o de regras do teto de gastos em audi\u00eancia p\u00fablica no Senado"},"content":{"rendered":"\n<p>A Comiss\u00e3o de Assuntos Econ\u00f4micos (CAE) do Senado debateu em audi\u00eancia p\u00fablica, no dia 24 de novembro, o <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/fichadetramitacao?idProposicao=2294651\">Projeto de Lei Complementar (PLP) 123\/2021<\/a>, que flexibiliza o teto de gastos de estados que negociaram d\u00edvidas com a Uni\u00e3o. A audi\u00eancia foi requerida pelo senador Zequinha Marinho (PSC-PA) e contou com a participa\u00e7\u00e3o do relator da mat\u00e9ria, senador Vanderlan Cardoso.<\/p>\n\n\n\n<p>A secret\u00e1ria de Fazenda do Goi\u00e1s, Cristiane Schmidt, representou o Comsefaz (Comit\u00ea Nacional dos Secret\u00e1rios de Fazenda dos Estados e do Distrito Federal). O senador Zequinha Marinho e o diretor da Institui\u00e7\u00e3o Fiscal Independente (IFI), Felipe Salto, manifestaram preocupa\u00e7\u00e3o com mais uma mudan\u00e7a de regras do teto de gastos.<\/p>\n\n\n\n<p>Os Estados argumentam, por\u00e9m, que a altera\u00e7\u00e3o ser\u00e1 bastante restrita. Cristiane Schmidt afirmou que livrar emendas parlamentares em geral e transfer\u00eancias da Uni\u00e3o do teto de gastos dos estados n\u00e3o vai comprometer a responsabilidade fiscal dos Estados e ainda possibilitar\u00e1 a amplia\u00e7\u00e3o dos investimentos locais.&nbsp;Ela observou que o equil\u00edbrio fiscal \u00e9 uma das grandes conquistas do Estados, mas ponderou que esses entes federados n\u00e3o podem emitir moeda nem d\u00edvidas.<\/p>\n\n\n\n<p>\u201cAcaba sendo um desservi\u00e7o ter as transfer\u00eancias da Uni\u00e3o dentro do meu teto. Se hoje deputados e senadores conseguem emendas para seus estados, eu digo que n\u00e3o quero porque tenho que colocar isso dentro do teto de gastos. Isso \u00e9 ruim para os Estados, porque perdemos recursos. Retirar essas transfer\u00eancias do teto n\u00e3o vai fazer o estado ser mais ou menos respons\u00e1vel\u201d, afirmou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"745\" height=\"327\" src=\"https:\/\/comsefaz.org.br\/wp-content\/uploads\/2021\/11\/Plenario-png.png\" alt=\"\" class=\"wp-image-2319\" srcset=\"https:\/\/comsefaz.org.br\/novo\/wp-content\/uploads\/2021\/11\/Plenario-png.png 745w, https:\/\/comsefaz.org.br\/novo\/wp-content\/uploads\/2021\/11\/Plenario-png-300x132.png 300w\" sizes=\"(max-width: 745px) 100vw, 745px\" \/><\/figure>\n\n\n\n<p>A subsecret\u00e1ria especial do Tesouro e Or\u00e7amento do Minist\u00e9rio da Economia, Pricilla Santana, observou que a medida \u00e9 uma flexibiliza\u00e7\u00e3o respons\u00e1vel, e n\u00e3o uma \u201cruptura do teto\u201d.&nbsp;\u201c\u00c9 uma flexibiliza\u00e7\u00e3o que eu entendo como respons\u00e1vel para atender os pleitos dos estados. O que estamos tirando agora n\u00e3o chega a 5% das transfer\u00eancias\u201d, disse.&nbsp;<\/p>\n\n\n\n<p>J\u00e1 aprovado pela C\u00e2mara dos Deputados, o projeto prev\u00ea que estados que celebraram acordo de renegocia\u00e7\u00e3o de d\u00edvidas com a Uni\u00e3o poder\u00e3o deduzir do teto de gastos transfer\u00eancias da Uni\u00e3o vinculadas a gastos espec\u00edficos, como a Contribui\u00e7\u00e3o de Interven\u00e7\u00e3o no Dom\u00ednio Econ\u00f4mico (Cide), sal\u00e1rio-educa\u00e7\u00e3o e Programa Nacional de Acesso ao Ensino T\u00e9cnico e Emprego (Pronatec). <\/p>\n\n\n\n<p>A proposta tamb\u00e9m livra do teto os valores oriundos de emendas das bancadas estaduais.\u00a0Hoje, transfer\u00eancias previstas na Constitui\u00e7\u00e3o e as emendas parlamentares individuais j\u00e1 est\u00e3o fora do limite para as despesas nos estados. O relator Vanderlan Cardoso disse que vai avaliar as pondera\u00e7\u00f5es dos participantes da audi\u00eancia e buscar um ponto de equil\u00edbrio para inclui-las no relat\u00f3rio.<\/p>\n\n\n\n<p><em>(Com informa\u00e7\u00f5es da Ag\u00eancia Senado)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Assuntos Econ\u00f4micos (CAE) do Senado debateu em audi\u00eancia p\u00fablica, no dia 24 de novembro, o Projeto de Lei Complementar (PLP) 123\/2021, que flexibiliza o teto de gastos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[118],"class_list":["post-2317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-responsabilidade-fiscal"],"acf":[],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/comsefaz.org.br\/novo\/wp-content\/uploads\/2021\/11\/Cristiane-Schmidt-Png.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/posts\/2317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/comments?post=2317"}],"version-history":[{"count":0,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/posts\/2317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/media\/2318"}],"wp:attachment":[{"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/media?parent=2317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/categories?post=2317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comsefaz.org.br\/novo\/wp-json\/wp\/v2\/tags?post=2317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}